{"id":686,"date":"2016-02-18T15:10:52","date_gmt":"2016-02-18T15:10:52","guid":{"rendered":"http:\/\/flatsome.dev\/?page_id=4041"},"modified":"2025-07-30T11:43:30","modified_gmt":"2025-07-30T03:43:30","slug":"simple-corporate","status":"publish","type":"page","link":"https:\/\/xmstonetools.com\/ja\/","title":{"rendered":"\u30db\u30fc\u30e0"},"content":{"rendered":"\n<div class=\"slider-wrapper relative\" id=\"slider-1932704926\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 6000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\n\n  <div class=\"banner has-hover\" id=\"banner-1657697810\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"700\" src=\"https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Banner-1.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n              <div class=\"height-fix is-invisible\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"700\" src=\"https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Banner-1.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Banner-1.jpg 1920w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Banner-1-600x219.jpg 600w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Banner-1-800x292.jpg 800w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Banner-1-1400x510.jpg 1400w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Banner-1-768x280.jpg 768w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Banner-1-1536x560.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/div>\n            \n<style>\n#banner-1657697810 .banner-bg img {\n  object-position: 62% 60%;\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover\" id=\"banner-616518105\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"372\" src=\"https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Banner-s-1400x510.jpg\" class=\"bg attachment-large size-large\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n              <div class=\"height-fix is-invisible\"><img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"372\" src=\"https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Banner-s-1400x510.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Banner-s-1400x510.jpg 1400w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Banner-s-600x219.jpg 600w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Banner-s-800x292.jpg 800w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Banner-s-768x280.jpg 768w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Banner-s-1536x560.jpg 1536w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Banner-s.jpg 1920w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><\/div>\n            \n<style>\n#banner-616518105 .banner-bg img {\n  object-position: 62% 68%;\n}\n<\/style>\n  <\/div>\n\n\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\n\t<section class=\"section\" id=\"section_1744333158\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<h1 style=\"text-align: center;\">Xiamen Sino Poly Industry Co., Ltd<\/h1>\n\t<div id=\"text-196287037\" class=\"text\">\n\t\t\n\n<h3 style=\"text-align: center;\">Supply various of tools for stone cutting, polishing, grinding and milling.<\/h3>\n\t\t\n<style>\n#text-196287037 {\n  font-size: 1.5rem;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1744333158 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1201204234\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\t<div class=\"ux-shape-divider ux-shape-divider--top ux-shape-divider--style-arrow\">\n\t\t<svg viewBox=\"0 0 1000 100\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n\t<path class=\"ux-shape-fill\" d=\"M1000 100H0L0 96H483L500 79L517 96H1000V100Z\"\/>\n<\/svg>\n\t<\/div>\n\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-small row-full-width align-equal align-center row-dashed\"  id=\"row-715796083\">\n\n\n\t<div id=\"col-524204022\" class=\"col medium-3 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  style=\"margin:0px 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:2px;\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"96\" height=\"96\" src=\"https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/e-bike-line.png\" class=\"attachment-medium size-medium\" alt=\"\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">High Quality<\/h5>\t\t\t\t\t\t\n\n<p>We always using high quality material and strict quality control system,assigning a specific personin charge of every step of productions.<\/p>\n<p>\u00a0<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1901176959\" class=\"col medium-3 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  style=\"margin:0px 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:2px;\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"96\" height=\"96\" src=\"https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/suitcase-line.png\" class=\"attachment-medium size-medium\" alt=\"\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">Own Factory<\/h5>\t\t\t\t\t\t\n\n<p>We have our own factory with professional engineers and sintered workers, they have more than 15 years experience in diamond tools industry.<\/p>\n<p>\u00a0<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-440630845\" class=\"col medium-3 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  style=\"margin:0px 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:2px;\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"96\" height=\"96\" src=\"https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/goblet-line.png\" class=\"attachment-medium size-medium\" alt=\"\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">Fast Delivery<\/h5>\t\t\t\t\t\t\n\n<p>We can ship out the ordered materials within 15 days. 10000 pcs of diamond segments can be ready for ship within 3 working days.<\/p>\n<p>\u00a0<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-155255412\" class=\"col medium-3 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  style=\"margin:0px 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:2px;\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"96\" height=\"96\" src=\"https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/basketball-line.png\" class=\"attachment-medium size-medium\" alt=\"\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">Sample Order<\/h5>\t\t\t\t\t\t\n\n<p>We accept sample order before normal order. We can send small quantity of diamond tools for customer testing before big order.<\/p>\n<p>\u00a0<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1201204234 {\n  padding-top: 20px;\n  padding-bottom: 20px;\n  background-color: rgb(255, 255, 255);\n}\n#section_1201204234 .ux-shape-divider--top svg {\n  height: 20px;\n  --divider-top-width: 100%;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_288607664\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-small row-full-width align-equal align-center row-dashed\"  id=\"row-1831847397\">\n\n\n\t<div id=\"col-63617622\" class=\"col medium-6 small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-3547790327\" class=\"text\">\n\t\t\n\n<h2 style=\"text-align: center;\">Our Products<\/h2>\n\t\t\n<style>\n#text-3547790327 {\n  font-size: 1.5rem;\n  line-height: 0.75;\n}\n<\/style>\n\t<\/div>\n\t\n<p>Includes stone cutting tools, grinding tools, polishing tools, diamond wire saw, diamond segment etc<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row row-small row-full-width align-equal align-center row-dashed row-box-shadow-3-hover\"  id=\"row-572873376\">\n\n\n\t<div id=\"col-802887825\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(255, 250, 238);\" >\n\t\t\t\n\t\t\t\n\n\n\t<a class=\"plain\" href=\"\/product\/stone-cutting-tools\/\" target=\"_blank\" rel=\"noopener\" >\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 100px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/20190911091822749\u5df2\u53bb\u5e95-400x400.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/20190911091822749\u5df2\u53bb\u5e95-400x400.png 400w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/20190911091822749\u5df2\u53bb\u5e95-300x300.png 300w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/20190911091822749\u5df2\u53bb\u5e95-100x100.png 100w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/20190911091822749\u5df2\u53bb\u5e95-600x600.png 600w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/20190911091822749\u5df2\u53bb\u5e95-800x800.png 800w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/20190911091822749\u5df2\u53bb\u5e95-280x280.png 280w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/20190911091822749\u5df2\u53bb\u5e95-768x768.png 768w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/20190911091822749\u5df2\u53bb\u5e95.png 999w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div id=\"text-4280935001\" class=\"text\">\n\t\t\n\n<h2>Cutting Tools<\/h2>\n\t\t\n<style>\n#text-4280935001 {\n  font-size: 1rem;\n}\n@media (min-width:850px) {\n  #text-4280935001 {\n    font-size: 1.25rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-823630468\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-823630468 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<a href=\"\/product\/stone-cutting-tools\/\" target=\"_blank\" class=\"button secondary is-link is-small\" rel=\"noopener\" >\n\t\t<span>Learn more<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\"><\/i><\/a>\n\n\n\n\t\t<\/div>\n\t<\/div>\n\t<\/a>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-551268638\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(235, 241, 251);\" >\n\t\t\t\n\t\t\t\n\n\n\t<a class=\"plain\" href=\"\/product\/stone-grinding-tools\/\" target=\"_blank\" rel=\"noopener\" >\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 100px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/20190912104108225\u5df2\u53bb\u5e95-400x400.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/20190912104108225\u5df2\u53bb\u5e95-400x400.png 400w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/20190912104108225\u5df2\u53bb\u5e95-300x300.png 300w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/20190912104108225\u5df2\u53bb\u5e95-100x100.png 100w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/20190912104108225\u5df2\u53bb\u5e95-600x600.png 600w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/20190912104108225\u5df2\u53bb\u5e95-800x800.png 800w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/20190912104108225\u5df2\u53bb\u5e95-280x280.png 280w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/20190912104108225\u5df2\u53bb\u5e95-768x768.png 768w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/20190912104108225\u5df2\u53bb\u5e95.png 999w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div id=\"text-2313126806\" class=\"text\">\n\t\t\n\n<h2>Grinding Tools<\/h2>\n\t\t\n<style>\n#text-2313126806 {\n  font-size: 1rem;\n}\n@media (min-width:850px) {\n  #text-2313126806 {\n    font-size: 1.25rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-1151756107\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1151756107 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<a href=\"\/product\/stone-grinding-tools\/\" target=\"_blank\" class=\"button secondary is-link is-small\" rel=\"noopener\" >\n\t\t<span>Learn more<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\"><\/i><\/a>\n\n\n\n\t\t<\/div>\n\t<\/div>\n\t<\/a>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1490520739\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(255, 241, 250);\" >\n\t\t\t\n\t\t\t\n\n\n\t<a class=\"plain\" href=\"\/product\/stone-polishing-tools\/\" target=\"_blank\" rel=\"noopener\" >\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 100px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/20190912100909878\u5df2\u53bb\u5e95-400x400.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/20190912100909878\u5df2\u53bb\u5e95-400x400.png 400w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/20190912100909878\u5df2\u53bb\u5e95-300x300.png 300w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/20190912100909878\u5df2\u53bb\u5e95-100x100.png 100w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/20190912100909878\u5df2\u53bb\u5e95-600x600.png 600w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/20190912100909878\u5df2\u53bb\u5e95-800x800.png 800w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/20190912100909878\u5df2\u53bb\u5e95-280x280.png 280w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/20190912100909878\u5df2\u53bb\u5e95-768x768.png 768w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/20190912100909878\u5df2\u53bb\u5e95.png 999w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div id=\"text-491891022\" class=\"text\">\n\t\t\n\n<h2>Polishing Tools<\/h2>\n\t\t\n<style>\n#text-491891022 {\n  font-size: 1rem;\n}\n@media (min-width:850px) {\n  #text-491891022 {\n    font-size: 1.25rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-2099498315\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-2099498315 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<a href=\"\/product\/stone-polishing-tools\/\" target=\"_blank\" class=\"button secondary is-link is-small\" rel=\"noopener\" >\n\t\t<span>Learn more<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\"><\/i><\/a>\n\n\n\n\t\t<\/div>\n\t<\/div>\n\t<\/a>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-429281914\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(237, 250, 254);\" >\n\t\t\t\n\t\t\t\n\n\n\t<a class=\"plain\" href=\"\/product\/diamond-wire-saw\/\" target=\"_blank\" rel=\"noopener\" >\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 100px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Wire-Saw-Icon-400x400.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Wire-Saw-Icon-400x400.png 400w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Wire-Saw-Icon-300x300.png 300w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Wire-Saw-Icon-100x100.png 100w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Wire-Saw-Icon-280x280.png 280w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Wire-Saw-Icon.png 550w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div id=\"text-3041502614\" class=\"text\">\n\t\t\n\n<h2>Diamond Wire<\/h2>\n\t\t\n<style>\n#text-3041502614 {\n  font-size: 1rem;\n}\n@media (min-width:850px) {\n  #text-3041502614 {\n    font-size: 1.25rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-1955551695\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1955551695 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<a href=\"\/product\/diamond-wire-saw\/\" target=\"_blank\" class=\"button secondary is-link is-small\" rel=\"noopener\" >\n\t\t<span>Learn more<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\"><\/i><\/a>\n\n\n\n\t\t<\/div>\n\t<\/div>\n\t<\/a>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-888937264\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(241, 234, 254);\" >\n\t\t\t\n\t\t\t\n\n\n\t<a class=\"plain\" href=\"\/product\/stone-cnc-tools\/\" target=\"_blank\" rel=\"noopener\" >\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 100px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"656\" height=\"400\" src=\"https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/CNC-Tools-Icon-656x400.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/CNC-Tools-Icon-656x400.png 656w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/CNC-Tools-Icon-600x366.png 600w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/CNC-Tools-Icon-768x468.png 768w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/CNC-Tools-Icon.png 992w\" sizes=\"auto, (max-width: 656px) 100vw, 656px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div id=\"text-373336699\" class=\"text\">\n\t\t\n\n<h2>CNC Tools<\/h2>\n\t\t\n<style>\n#text-373336699 {\n  font-size: 1rem;\n}\n@media (min-width:850px) {\n  #text-373336699 {\n    font-size: 1.25rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-1925141563\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1925141563 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<a href=\"\/product\/stone-cnc-tools\/\" target=\"_blank\" class=\"button secondary is-link is-small\" rel=\"noopener\" >\n\t\t<span>Learn more<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\"><\/i><\/a>\n\n\n\n\t\t<\/div>\n\t<\/div>\n\t<\/a>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1936923794\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(228, 248, 246);\" >\n\t\t\t\n\t\t\t\n\n\n\t<a class=\"plain\" href=\"\/product\/stone-milling-tools\/\" target=\"_blank\" rel=\"noopener\" >\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 100px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"521\" height=\"400\" src=\"https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Milling-Tools-Icon-521x400.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Milling-Tools-Icon-521x400.png 521w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Milling-Tools-Icon-600x461.png 600w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Milling-Tools-Icon-768x590.png 768w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Milling-Tools-Icon.png 805w\" sizes=\"auto, (max-width: 521px) 100vw, 521px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div id=\"text-2692353270\" class=\"text\">\n\t\t\n\n<h2>Milling Tools<\/h2>\n\t\t\n<style>\n#text-2692353270 {\n  font-size: 1rem;\n}\n@media (min-width:850px) {\n  #text-2692353270 {\n    font-size: 1.25rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-1761720622\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1761720622 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<a href=\"\/product\/stone-milling-tools\/\" target=\"_blank\" class=\"button secondary is-link is-small\" rel=\"noopener\" >\n\t\t<span>Learn more<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\"><\/i><\/a>\n\n\n\n\t\t<\/div>\n\t<\/div>\n\t<\/a>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\n<style>\n#row-572873376 > .col > .col-inner {\n  padding: 30px 20px 30px 20px;\n  border-radius: 5px;\n}\n@media (min-width:850px) {\n  #row-572873376 > .col > .col-inner {\n    padding: 70px 20px 70px 20px;\n  }\n}\n<\/style>\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_288607664 {\n  padding-top: 40px;\n  padding-bottom: 40px;\n}\n@media (min-width:550px) {\n  #section_288607664 {\n    padding-top: 10px;\n    padding-bottom: 10px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1506977595\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-small row-full-width align-equal align-center row-dashed\"  id=\"row-515786974\">\n\n\n\t<div id=\"col-605585902\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<h2>What They Say<\/h2>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"slider-wrapper relative\" id=\"slider-1443315715\" >\n    <div class=\"slider slider-nav-dots-simple slider-nav-circle slider-nav-large slider-nav-dark slider-nav-outside slider-style-normal slider-show-nav\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 3000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": false,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\n<div class=\"row row-small row-full-width align-equal align-center row-dashed\"  id=\"row-1965381041\">\n\n\n\t<div id=\"col-828481508\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p class=\"lead\">The professionalism and response time left me speechless. The quality was amazing and i got exactly what i wanted. With maintenance service we are definitely sticking with them.<\/p>\n\n\t\t<div class=\"icon-box featured-box circle icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 50px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/avatar-placeholder-400x400.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/avatar-placeholder-400x400.png 400w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/avatar-placeholder-300x300.png 300w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/avatar-placeholder-100x100.png 100w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/avatar-placeholder-600x600.png 600w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/avatar-placeholder-800x800.png 800w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/avatar-placeholder-280x280.png 280w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/avatar-placeholder-768x768.png 768w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/avatar-placeholder.png 1000w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<p><strong>John Holt<\/strong><br \/>Factory Director<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-828481508 > .col-inner {\n  margin: 0px 0px 20px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-974592221\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p class=\"lead\">The scale of the project proved to be quite a challenge, but they presented there plan executed it without a problem as true professionals and delivered the product on time and with top quality materials, just a great experience.<\/p>\n\n\t\t<div class=\"icon-box featured-box circle icon-box-left text-left\"  >\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<p><strong>JANE ADAMS<\/strong><br \/>Project Manager<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-974592221 > .col-inner {\n  margin: 0px 0px 20px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\n<style>\n#row-1965381041 > .col > .col-inner {\n  padding: 30px 30px 30px 30px;\n  background-color: rgb(255,255,255);\n}\n<\/style>\n<\/div>\n<div class=\"row row-small row-full-width align-equal align-center row-dashed\"  id=\"row-387194029\">\n\n\n\t<div id=\"col-1068817843\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p class=\"lead\">The scale of the project proved to be quite a challenge, but they presented there plan executed it without a problem as true professionals and delivered the product on time and with top quality materials, just a great experience.<\/p>\n\n\t\t<div class=\"icon-box featured-box circle icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 50px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/87\" alt=\"\"\/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<p><strong>MICHAEL CLAY<\/strong><br \/>Designer<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1068817843 > .col-inner {\n  margin: 0px 0px 20px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1948502944\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p class=\"lead\">At our location precise calibrating was nearly impossible, but Mactotec\u2019s team went above and beyond to finish the job. With highly professional attitude they completed the job with top quality results.<\/p>\n\n\t\t<div class=\"icon-box featured-box circle icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 50px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/87\" alt=\"\"\/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n<p><strong>Angela Smith<\/strong><br \/>CEO<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1948502944 > .col-inner {\n  margin: 0px 0px 20px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\n<style>\n#row-387194029 > .col > .col-inner {\n  padding: 30px 30px 30px 30px;\n  background-color: rgb(255,255,255);\n}\n<\/style>\n<\/div>\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1506977595 {\n  padding-top: 60px;\n  padding-bottom: 60px;\n  background-color: rgb(245, 247, 251);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_808600973\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:1px 0px 1px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-small row-full-width align-equal align-center row-dashed\"  id=\"row-178202646\">\n\n\n\t<div id=\"col-1384815897\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2 class=\"uppercase\">Latest News<\/h2>\n<p>Some usefull information &amp; knowledge about cutting tools, polishing tools etc.<\/p>\n<p>\u00a0<\/p>\n<a class=\"button primary\" >\n\t\t<span>Our blog<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1060004282\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n  \n    <div class=\"row large-columns-2 medium-columns- small-columns-1 has-shadow row-box-shadow-1 slider row-slider slider-nav-circle\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : false}' >\n\n  <div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-vertical box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" style=\"width:40%;\">\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:223px;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/xmstonetools.com\/ja\/%e7%92%b0%e7%8a%b6%e9%9b%bb%e7%9d%80%e3%83%80%e3%82%a4%e3%83%a4%e3%83%a2%e3%83%b3%e3%83%89%e3%83%af%e3%82%a4%e3%83%a4%e3%83%bc\/\" class=\"plain\" aria-label=\"annular electroplated diamond wire\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"733\" height=\"400\" src=\"https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/annular-electroplated-diamond-wire-1-733x400.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"annular electroplated diamond wire-1\" srcset=\"https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/annular-electroplated-diamond-wire-1-733x400.png 733w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/annular-electroplated-diamond-wire-1-768x419.png 768w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/annular-electroplated-diamond-wire-1-600x328.png 600w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/annular-electroplated-diamond-wire-1.png 923w\" sizes=\"auto, (max-width: 733px) 100vw, 733px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" style=\"background-color:rgb(255, 255, 255);\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/xmstonetools.com\/ja\/%e7%92%b0%e7%8a%b6%e9%9b%bb%e7%9d%80%e3%83%80%e3%82%a4%e3%83%a4%e3%83%a2%e3%83%b3%e3%83%89%e3%83%af%e3%82%a4%e3%83%a4%e3%83%bc\/\" class=\"plain\">annular electroplated diamond wire<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tMany individuals may be unfamiliar with diamond cutting blades.In fact, diamond saw blades are a [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-circle\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">29<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">11\u6708<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-vertical box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" style=\"width:40%;\">\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:223px;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/xmstonetools.com\/ja\/%e5%a4%a7%e7%90%86%e7%9f%b3%e3%81%ae%e9%8b%b8%e5%88%83%e3%81%ae%e7%b4%b9%e4%bb%8b\/\" class=\"plain\" aria-label=\"Introduce of marble saw blade\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Marble-Saw-Blade-400x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Marble Saw Blade\" srcset=\"https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Marble-Saw-Blade-400x400.jpg 400w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Marble-Saw-Blade-280x280.jpg 280w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Marble-Saw-Blade-300x300.jpg 300w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Marble-Saw-Blade-600x600.jpg 600w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Marble-Saw-Blade-100x100.jpg 100w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Marble-Saw-Blade-120x120.jpg 120w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Marble-Saw-Blade.jpg 750w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" style=\"background-color:rgb(255, 255, 255);\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/xmstonetools.com\/ja\/%e5%a4%a7%e7%90%86%e7%9f%b3%e3%81%ae%e9%8b%b8%e5%88%83%e3%81%ae%e7%b4%b9%e4%bb%8b\/\" class=\"plain\">Introduce of marble saw blade<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tMany individuals may be unfamiliar with diamond cutting blades. In fact, diamond saw blades are [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-circle\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">29<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">11\u6708<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-vertical box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" style=\"width:40%;\">\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:223px;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/xmstonetools.com\/ja\/%e5%a4%a7%e7%90%86%e7%9f%b3%e7%a0%94%e7%a3%a8%e7%94%a8%e5%85%b7%e3%81%ae%e7%94%a8%e9%80%94\/\" class=\"plain\" aria-label=\"Application of marble polishing tools\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"794\" height=\"318\" src=\"https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Application-of-marble-polishing-tools-1.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Application of marble polishing tools-1\" srcset=\"https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Application-of-marble-polishing-tools-1.png 794w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Application-of-marble-polishing-tools-1-768x308.png 768w, https:\/\/xmstonetools.com\/wp-content\/uploads\/2022\/11\/Application-of-marble-polishing-tools-1-600x240.png 600w\" sizes=\"auto, (max-width: 794px) 100vw, 794px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" style=\"background-color:rgb(255, 255, 255);\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/xmstonetools.com\/ja\/%e5%a4%a7%e7%90%86%e7%9f%b3%e7%a0%94%e7%a3%a8%e7%94%a8%e5%85%b7%e3%81%ae%e7%94%a8%e9%80%94\/\" class=\"plain\">Application of marble polishing tools<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tNowadays, marble is mostly used to decorate the ground.The marble should be all around kept [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-circle\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">29<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">11\u6708<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_808600973 {\n  padding-top: 43px;\n  padding-bottom: 43px;\n  min-height: 276px;\n  background-color: rgb(241, 241, 241);\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"message-box relative dark\" style=\"padding-top:36px;padding-bottom:36px;\"><div class=\"message-box-bg-image bg-fill fill\" ><\/div><div class=\"message-box-bg-overlay bg-fill fill\" style=\"background-color:rgb(74, 74, 74);\"><\/div><div class=\"container relative\"><div class=\"inner last-reset\">\n\n<div class=\"row row-small row-full-width align-middle align-center\"  id=\"row-1708604282\">\n\n\n\t<div id=\"col-115146978\" class=\"col medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2 style=\"text-align: center;\">Contact Us Today\u00a0<\/h2>\n<p style=\"text-align: center;\">Our professional team are ready to work with you.<\/p>\n<p>\u00a0<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2023708711\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner text-right\"  >\n\t\t\t\n\t\t\t\n\n<a class=\"button white is-outline is-large popmake-1134\" >\n\t<i class=\"icon-star\" aria-hidden=\"true\"><\/i>\t<span>Contact Us<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n<\/div><\/div><\/div>\n\n","protected":false},"excerpt":{"rendered":"Nowadays, marble is mostly used to decorate the ground.The marble should be all around kept up with when it is utilized. The gas marble can only be used more effectively and for longer periods of time if it is well-maintained. However, how well-versed are you in the marble polishing procedure? When polishing marble, there are [...]","protected":false},"author":1,"featured_media":621,"parent":0,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-686","page","type-page","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/xmstonetools.com\/ja\/wp-json\/wp\/v2\/pages\/686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xmstonetools.com\/ja\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/xmstonetools.com\/ja\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/xmstonetools.com\/ja\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/xmstonetools.com\/ja\/wp-json\/wp\/v2\/comments?post=686"}],"version-history":[{"count":52,"href":"https:\/\/xmstonetools.com\/ja\/wp-json\/wp\/v2\/pages\/686\/revisions"}],"predecessor-version":[{"id":1936,"href":"https:\/\/xmstonetools.com\/ja\/wp-json\/wp\/v2\/pages\/686\/revisions\/1936"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xmstonetools.com\/ja\/wp-json\/wp\/v2\/media\/621"}],"wp:attachment":[{"href":"https:\/\/xmstonetools.com\/ja\/wp-json\/wp\/v2\/media?parent=686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}